{"id":25,"date":"2024-07-09T15:55:10","date_gmt":"2024-07-09T07:55:10","guid":{"rendered":"https:\/\/www.pkcell.com\/?page_id=25"},"modified":"2026-03-18T16:22:47","modified_gmt":"2026-03-18T08:22:47","slug":"wystawa","status":"publish","type":"page","link":"https:\/\/www.pkcell.com\/pl\/exhibition\/","title":{"rendered":"Wystawa"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"25\" class=\"elementor elementor-25\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-becc49c maincontent e-con-full e-flex e-con e-parent\" data-id=\"becc49c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97e72ee elementor-widget elementor-widget-ucaddon_breadcrumb\" data-id=\"97e72ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Breadcrumb -->\n\n<div class=\"breadcrumb\">\n  <div class=\"maincontainer\">\n    <div class=\"box\">\n      <a href=\"\/pl\/\">Strona g\u0142\u00f3wna<\/a>\n      <span> - <\/span>\n\n\n<a href=\"https:\/\/www.pkcell.com\/pl\/exhibition\/\" class=\"on\">Wystawa<\/a>\n\n\n\n    <\/div>\n  <\/div>\n<\/div>\n<!-- end Breadcrumb -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b46ded3 elementor-widget elementor-widget-ucaddon_page_introduce_title\" data-id=\"b46ded3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_page_introduce_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Page Introduce Title -->\n\n<div class=\"padt40 padb40 introduce w8\">\n  <div class=\"maincontainer\" style=\"background-image\">\n    <div class=\"current_title\">\n      <h1 class=\"size42 wow fadeInUpSmall\">\n                \tWystawa\n              <\/h1>\n      <div class=\"size18 text wow fadeInUpSmall\">\n        Odkryj nasz\u0105 podr\u00f3\u017c po targach\nRzut oka na najlepsze z naszych innowacji podczas globalnych wydarze\u0144 bran\u017cowych\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n<!-- end Page Introduce Title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aed1f59 e-flex e-con-boxed e-con e-parent\" data-id=\"aed1f59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45b20cb elementor-widget elementor-widget-html\" data-id=\"45b20cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"video-container\" style=\"position: relative; padding-bottom: 56.25%; height: 0; overflow: hidden; max-width: 100%; background: #000;\">\r\n    <iframe \r\n        style=\"position: absolute; top: 0; left: 0; width: 100%; height: 100%; border: 0;\"\r\n        src=\"https:\/\/www.youtube.com\/embed\/JSB7tW7WMd0\" \r\n        title=\"PKCELL Battery - Leading Battery Manufacturer &amp; Solution Provider\" \r\n        frameborder=\"0\" \r\n        allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" \r\n        referrerpolicy=\"strict-origin-when-cross-origin\" \r\n        allowfullscreen>\r\n    <\/iframe>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef81833 e-grid e-con-boxed e-con e-parent\" data-id=\"ef81833\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffe3b7b elementor-widget elementor-widget-spacer\" data-id=\"ffe3b7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb7f6c6 e-con-full padb100 exhibition e-flex e-con e-parent\" data-id=\"cb7f6c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19e215b maincontainer elementor-widget elementor-widget-ucaddon_post_magazine_grid\" data-id=\"19e215b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_post_magazine_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Magazine Grid -->\n\t\t<link id='font-awesome-css' href='https:\/\/www.pkcell.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/www.pkcell.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Post Magazine Grid *\/\n\n\n\n#uc_post_magazine_grid_elementor_19e215b *\n{\n  box-sizing:border-box;\n}\n#uc_post_magazine_grid_elementor_19e215b\n{\n  display: grid;\n  grid-auto-rows: 1fr;\n}\n\n#uc_post_magazine_grid_elementor_19e215b div.ue-grid-item\n{\n  overflow:hidden;\n  display:flex;\n  position:relative;\n}\n\n#uc_post_magazine_grid_elementor_19e215b .ue-grid-item-intro{\n  position: relative;\n  z-index: 1;\n}\n\n#uc_post_magazine_grid_elementor_19e215b .ue-grid-item-image img\n{\n  width:100%;\n  display:block;\n}\n\n\n#uc_post_magazine_grid_elementor_19e215b.ue-layout-cover .ue-grid-item-image\n{\n  position:absolute;\n  top:0;\n  left:0;\n  bottom:0;\n  right:0;\n}\n\n#uc_post_magazine_grid_elementor_19e215b.ue-layout-cover .ue-grid-item-image img\n{\n  height:100%;\n  object-fit: cover;\n}\n\n#uc_post_magazine_grid_elementor_19e215b.ue-layout-cover .ue-grid-item-content\n{\n  position:absolute;\n  width:100%;\n  bottom:0px;\n}\n\n#uc_post_magazine_grid_elementor_19e215b .ue-grid-item-image-overlay\n{\n  position:absolute;\n  z-index: 1;\n  width:100%;\n  top:0;\n  display:block;\n  bottom:0;\n  height:100%;\n  transition:0.3s;\n}\n\n.ue-grid-item-title a\n{\n  font-size:21px;\n  font-weight:bold;\n  position: relative;\n  z-index: 1;  \n}\n\n.ue-grid-item-category a\n{\n  display:inline-block;\n  font-size:10px;\n  text-transform:uppercase;\n  position: relative;\n  z-index: 1; \n}\n\n#uc_post_magazine_grid_elementor_19e215b .uc_more_btn{\n\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_post_magazine_grid_elementor_19e215b .ue-grid-item-meta-data\n{\n  display:flex;\n  flex-wrap: wrap;\n}\n\n.ue-grid-item-meta-data\n{\n  font-size:12px;\n}\n\n#uc_post_magazine_grid_elementor_19e215b .ue-grid-item-meta-data-icon\n{\n  line-height:1em;\n}\n\n#uc_post_magazine_grid_elementor_19e215b .ue-grid-item-meta-data-icon svg\n{\n  width:1em;\n  height:1em;\n}\n\n\n\n#uc_post_magazine_grid_elementor_19e215b .ue-date-calendar\n{\n      position:absolute;\n      top:0px;\n     left:0px;\n     text-align:center;\n    }\n\n@media only screen and (max-width: 600px) {\n  #uc_post_magazine_grid_elementor_19e215b div.ue-grid-item\n  {\n    grid-column: span 1;\n    grid-row: span 1;\n  }\n  #uc_post_magazine_grid_elementor_19e215b\n  {\n  grid-template-columns: repeat(1, 1fr);\n  }\n}\n\n<\/style>\n\n<div id=\"uc_post_magazine_grid_elementor_19e215b\" class=\"post_magazine_grid ue-layout-cover uc-items-wrapper uc-filterable-grid\"  data-ajax='true'  data-filterbehave='ajax'  querydata='{&quot;count_posts&quot;:5,&quot;total_posts&quot;:20,&quot;page&quot;:1,&quot;num_pages&quot;:4}'>\n\t\n<div class=\"ue-grid-item wow fadeInUpSmall\">\n  \n\t<div class=\"ue-grid-item-image\">\n       \n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pkcell.com\/wp-content\/uploads\/batteries-exhibition-768x576.jpg\"  alt=\"batteries exhibition\" width=\"768\" height=\"576\">  \n      \t\n\t        \n      <a class=\"ue-grid-item-image-overlay\" href=\"https:\/\/www.pkcell.com\/pl\/2026-hktdc-hong-kong-electronics-fair-spring-edition\/\" aria-label=\"Read more about 2026 HKTDC Hong Kong Electronics Fair (Spring Edition)\" ><\/a>\n    <\/div>\n    <div class=\"ue-grid-item-content\">\n      \n                <div class=\"ue-grid-item-meta-data\">\n    <div class=\"ue-grid-item-meta-data-date\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span> 2026-04-16<\/div>                  \n  <\/div>\n      \n      <div class=\"ue-grid-item-title\"><a href=\"https:\/\/www.pkcell.com\/pl\/2026-hktdc-hong-kong-electronics-fair-spring-edition\/\">2026 HKTDC Hong Kong Electronics Fair (Spring Edition)<\/a><\/div>      \n            \n                <\/div>\n  \n    \n    \n  \n<\/div>\n\n<div class=\"ue-grid-item wow fadeInUpSmall\">\n  \n\t<div class=\"ue-grid-item-image\">\n       \n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pkcell.com\/wp-content\/uploads\/34th-EST-china-fair-exhibition-768x512.webp\"  alt=\"34th EST china fair exhibition\" width=\"768\" height=\"512\">  \n      \t\n\t        \n      <a class=\"ue-grid-item-image-overlay\" href=\"https:\/\/www.pkcell.com\/pl\/34th-east-china-fair-ecf-2026-powering-the-next-generation-of-global-trade\/\" aria-label=\"Read more about The 34th East China Fair (ECF) 2026 \u2013 Powering the Next Generation of Global Trade\" ><\/a>\n    <\/div>\n    <div class=\"ue-grid-item-content\">\n      \n                <div class=\"ue-grid-item-meta-data\">\n    <div class=\"ue-grid-item-meta-data-date\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span> 2026-03-05<\/div>                  \n  <\/div>\n      \n      <div class=\"ue-grid-item-title\"><a href=\"https:\/\/www.pkcell.com\/pl\/34th-east-china-fair-ecf-2026-powering-the-next-generation-of-global-trade\/\">The 34th East China Fair (ECF) 2026 \u2013 Powering the Next Generation of Global Trade<\/a><\/div>      \n            \n                <\/div>\n  \n    \n    \n  \n<\/div>\n\n<div class=\"ue-grid-item wow fadeInUpSmall\">\n  \n\t<div class=\"ue-grid-item-image\">\n       \n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pkcell.com\/wp-content\/uploads\/pkcell-green-energy_compressed-768x576.jpg\"  alt=\"pkcell green energy_compressed\" width=\"768\" height=\"576\">  \n      \t\n\t        \n      <a class=\"ue-grid-item-image-overlay\" href=\"https:\/\/www.pkcell.com\/pl\/pkcells-strategic-breakthroughs-at-ces-2026\/\" aria-label=\"Read more about PKCELL\u2019s Strategic Breakthroughs at CES 2026\" ><\/a>\n    <\/div>\n    <div class=\"ue-grid-item-content\">\n      \n                <div class=\"ue-grid-item-meta-data\">\n    <div class=\"ue-grid-item-meta-data-date\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span> 2026-01-22<\/div>                  \n  <\/div>\n      \n      <div class=\"ue-grid-item-title\"><a href=\"https:\/\/www.pkcell.com\/pl\/pkcells-strategic-breakthroughs-at-ces-2026\/\">PKCELL\u2019s Strategic Breakthroughs at CES 2026<\/a><\/div>      \n            \n                <\/div>\n  \n    \n    \n  \n<\/div>\n\n<div class=\"ue-grid-item wow fadeInUpSmall\">\n  \n\t<div class=\"ue-grid-item-image\">\n       \n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pkcell.com\/wp-content\/uploads\/HK-Electronic-Fair-768x576.jpg\"  alt=\"HK Electronic Fair\" width=\"768\" height=\"576\">  \n      \t\n\t        \n      <a class=\"ue-grid-item-image-overlay\" href=\"https:\/\/www.pkcell.com\/pl\/hktdc-hong-kong-electronics-fair-autumn-edition\/\" aria-label=\"Read more about HKTDC Hong Kong Electronics Fair (Autumn Edition)\" ><\/a>\n    <\/div>\n    <div class=\"ue-grid-item-content\">\n      \n                <div class=\"ue-grid-item-meta-data\">\n    <div class=\"ue-grid-item-meta-data-date\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span> 2025-11-24<\/div>                  \n  <\/div>\n      \n      <div class=\"ue-grid-item-title\"><a href=\"https:\/\/www.pkcell.com\/pl\/hktdc-hong-kong-electronics-fair-autumn-edition\/\">HKTDC Hong Kong Electronics Fair (Autumn Edition)<\/a><\/div>      \n            \n                <\/div>\n  \n    \n    \n  \n<\/div>\n\n<div class=\"ue-grid-item wow fadeInUpSmall\">\n  \n\t<div class=\"ue-grid-item-image\">\n       \n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pkcell.com\/wp-content\/uploads\/semi-solid-battery-768x502.jpg\"  alt=\"semi-solid battery\" width=\"768\" height=\"502\">  \n      \t\n\t        \n      <a class=\"ue-grid-item-image-overlay\" href=\"https:\/\/www.pkcell.com\/pl\/pkcell-at-the-138th-canton-fair-autumn-2025\/\" aria-label=\"Read more about \u00a0PKCELL at the 138th Canton Fair (Autumn 2025)\" ><\/a>\n    <\/div>\n    <div class=\"ue-grid-item-content\">\n      \n                <div class=\"ue-grid-item-meta-data\">\n    <div class=\"ue-grid-item-meta-data-date\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span> 2025-11-24<\/div>                  \n  <\/div>\n      \n      <div class=\"ue-grid-item-title\"><a href=\"https:\/\/www.pkcell.com\/pl\/pkcell-at-the-138th-canton-fair-autumn-2025\/\">\u00a0PKCELL at the 138th Canton Fair (Autumn 2025)<\/a><\/div>      \n            \n                <\/div>\n  \n    \n    \n  \n<\/div>\n\n<\/div>\n\n\n<!-- end Post Magazine Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d504b25 elementor-widget elementor-widget-ucaddon_archive_pagination\" data-id=\"d504b25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_archive_pagination.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Pagination -->\n\n<style>\/* widget: Post Pagination *\/\n\n#uc_archive_pagination_elementor_d504b25 nav\n{\n  padding:0px;\n  margin:0px;\n}\n\n#uc_archive_pagination_elementor_d504b25 \n{\n  display:flex;\n  flex-wrap: wrap;\n  justify-content:center;\n}\n\n#uc_archive_pagination_elementor_d504b25 .nav-links\n{\n  display:flex;\n  justify-content:center;\n}\n\n#uc_archive_pagination_elementor_d504b25 .nav-links > *\n{\n}\n\n#uc_archive_pagination_elementor_d504b25 .page-numbers\n{\n  display:flex;\n  \n  align-items:center;\n  justify-content:center;\n  transition:0.3s;\n  line-height:1em;\n}\n\n\n#uc_archive_pagination_elementor_d504b25 a.page-numbers, #uc_archive_pagination_elementor_d504b25 .dots\n{\n  color:#043D82;\n  background-color:#E5EBF2;\n}\n\n#uc_archive_pagination_elementor_d504b25 a.page-numbers:hover\n{\n  color:#FFFFFF;\n  background-color:#043D82;\n}\n\n#uc_archive_pagination_elementor_d504b25 .page-numbers.current,\n#uc_archive_pagination_elementor_d504b25 .page-numbers.current:hover\n{\n  background-color:#043D82;\n  color:#ffffff;\n}\n\n\n#uc_archive_pagination_elementor_d504b25 .page-numbers.prev, #uc_archive_pagination_elementor_d504b25 .page-numbers.next\n{\n  padding-left:15px;\n  padding-right:15px;\n}\n\n\n\n#uc_archive_pagination_elementor_d504b25 .prev:before {\n   font-family: \"Font Awesome 5 Free\";\n   content: \"\\f053\";\n   display: inline-block;\n   vertical-align: middle;\n   font-weight: 900;\n   }\n\n#uc_archive_pagination_elementor_d504b25 .next:after {\n   font-family: \"Font Awesome 5 Free\";\n   content: \"\\f054\";\n   display: inline-block;\n   vertical-align: middle;\n   font-weight: 900;\n   }\n\n#uc_archive_pagination_elementor_d504b25.uc-ajax-loading{\n\topacity:1 !important;\n}\n\n#uc_archive_pagination_elementor_d504b25.uc-ajax-loading .current{\n\tposition:relative;\n    overflow:hidden;\n}\n\n\n#uc_archive_pagination_elementor_d504b25.uc-ajax-loading .current:before{\n  content: \"\";\n  display:block;\n  width:100%;\n  height:100%;\n  box-sizing:border-box;\n  position:absolute;\n  top:0px;\n  left:0px;\n  background-color: #c2c2c2;\n  animation: uc-spinning-border 0.5s linear infinite;\n  opacity:50%;\n  border-radius:inherit;\n}\n\n@keyframes uc-spinning-border {\n\t0%{transform: scale(0);}\n\t100%{transform: scale(1); }\t\n}\n\n\n\n<\/style>\n\n<div id=\"uc_archive_pagination_elementor_d504b25\" class=\"archive_pagination uc-filter-pagination\">\n<span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.pkcell.com\/pl\/exhibition\/2\/\" data-e-disable-page-transition=\"true\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.pkcell.com\/pl\/exhibition\/3\/\" data-e-disable-page-transition=\"true\">3<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.pkcell.com\/pl\/exhibition\/4\/\" data-e-disable-page-transition=\"true\">4<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.pkcell.com\/pl\/exhibition\/2\/\" data-e-disable-page-transition=\"true\"><\/a>\n<\/div>\n<!-- end Post Pagination -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d488b9 e-con-full e-flex e-con e-parent\" data-id=\"1d488b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-701389f elementor-widget elementor-widget-ucaddon_contact_submit_form\" data-id=\"701389f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_contact_submit_form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Contact Submit Form -->\n\n<div class=\"padb136 Get_in_Touch\">\n\t\t\t\t<div class=\"maincontainer\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<div class=\"current_title center\">\n\t\t\t\t\t\t\t<h3 class=\"size42 wow fadeInUpSmall\">\n\t\t\t\t\t\t\t\tGAT A QUOTE\n\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<div class=\"size20 text wow fadeInUpSmall\">\n\t\t\t\t\t\t\t\tMo\u017cesz skontaktowa\u0107 si\u0119 z nami telefonicznie, e-mailem lub wype\u0142niaj\u0105c poni\u017cszy formularz kontaktowy. Staramy si\u0119 odpowiada\u0107 na wszystkie zapytania w ci\u0105gu 24 godzin.\t\t\t\t\t\t\t\n                          \t<\/div>\n\t\t\t\t\t\t<\/div>\n                    \n\n\t\t\t\t\t\t<div class=\"wrap\">\n\t\t\t\t\t\t\t<div class=\"infor\">\n\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<li class=\"wow fadeInUpSmall\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t    \t\t\t\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/www.pkcell.com\/wp-content\/uploads\/icon19.png\">\n\t\t\t\t    \t\t\t\t\t\t<\/div>\n\t\t\t\t    \t\t\t\t\t\t<div class=\"size18 text\">\n\t\t\t\t    \t\t\t\t\t\t\t<div class=\"t1\">\n\t\t\t\t    \t\t\t\t\t\t\t\tE-mail\n\t\t\t\t    \t\t\t\t\t\t\t<\/div>\n\t\t\t\t    \t\t\t\t\t\t\t<div class=\"t2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tinfo@pkcell.com\n\t\t\t\t    \t\t\t\t\t\t\t<\/div>\n\t\t\t\t    \t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li class=\"wow fadeInUpSmall\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t    \t\t\t\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/www.pkcell.com\/wp-content\/uploads\/icon20.png\">\n\t\t\t\t    \t\t\t\t\t\t<\/div>\n\t\t\t\t    \t\t\t\t\t\t<div class=\"size18 text\">\n\t\t\t\t    \t\t\t\t\t\t\t<div class=\"t1\">\n\t\t\t\t    \t\t\t\t\t\t\t\tAdres firmy\n\t\t\t\t    \t\t\t\t\t\t\t<\/div>\n\t\t\t\t    \t\t\t\t\t\t\t<div class=\"t2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t9. pi\u0119tro, blok B, Hongrongyuan North Station Center, nr 328, Mintang Road, Longhua District, Shenzhen, Chiny, 518110\n\t\t\t\t    \t\t\t\t\t\t\t<\/div>\n\t\t\t\t    \t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"formBox\">\n                              \t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f345-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"345\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pl\/wp-json\/wp\/v2\/pages\/25#wpcf7-f345-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formularz kontaktowy\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pl\/wp-json\/wp\/v2\/pages\/25#wpcf7-f345-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"345\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f345-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"inputLi wow fadeInUpSmall\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required size18\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nazwa*\" value=\"\" type=\"text\" name=\"Name\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"inputLi wow fadeInUpSmall\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email size18\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail*\" value=\"\" type=\"email\" name=\"Email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"inputLi wow fadeInUpSmall\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"WhatsAppTelPhone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel size18\" aria-invalid=\"false\" placeholder=\"WhatsApp (z kodem kraju)\" value=\"\" type=\"tel\" name=\"WhatsAppTelPhone\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"inputLi wow fadeInUpSmall\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text size18\" aria-invalid=\"false\" placeholder=\"Firma\" value=\"\" type=\"text\" name=\"Company\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"textareaLi wow fadeInUpSmall\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required size18\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Wiadomo\u015b\u0107*\" name=\"Message\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<div class=\"inputBtn wow fadeInUpSmall\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner size18\" type=\"submit\" value=\"POBIERZ OFERT\u0118\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pl\"\/><\/form>\n<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n<!-- end Contact Submit Form -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Home &#8211; Exhibition Discover our trade show journey a glance at the best of our innovations at global industry events 2026-03-05 The 34th East China Fair (ECF) 2026 \u2013 Powering the Next Generation of Global Trade 2026-01-22 PKCELL\u2019s Strategic Breakthroughs at CES 2026 2025-11-24 HKTDC Hong Kong Electronics Fair (Autumn Edition) 2025-11-24 \u00a0PKCELL at the [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.pkcell.com\/pl\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pkcell.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pkcell.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pkcell.com\/pl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pkcell.com\/pl\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":12,"href":"https:\/\/www.pkcell.com\/pl\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":61821,"href":"https:\/\/www.pkcell.com\/pl\/wp-json\/wp\/v2\/pages\/25\/revisions\/61821"}],"wp:attachment":[{"href":"https:\/\/www.pkcell.com\/pl\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}